{"id":743,"date":"2024-01-30T17:02:53","date_gmt":"2024-01-30T18:02:53","guid":{"rendered":"https:\/\/persian.tgmweb.ir\/%d8%a7%d8%ae%d8%a8%d8%a7%d8%b1-%d9%88-%d9%85%d9%82%d8%a7%d9%84%d8%a7%d8%aa\/"},"modified":"2024-03-11T07:46:00","modified_gmt":"2024-03-11T08:46:00","slug":"news-and-articles","status":"publish","type":"page","link":"https:\/\/parsian-ebc.com\/en\/news-and-articles\/","title":{"rendered":"News and articles"},"content":{"rendered":"\n  <div class=\"banner has-hover\" id=\"banner-837746537\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-2112393525\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-2112393525 {\n  width: 60%;\n}\n#text-box-2112393525 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-2112393525 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-837746537 {\n  padding-top: 200px;\n}\n#banner-837746537 .bg.bg-loaded {\n  background-image: url(https:\/\/parsian-ebc.com\/wp-content\/uploads\/2024\/01\/architect-engineer-using-laptop-working-with-yellow-helmet.jpg);\n}\n#banner-837746537 .bg {\n  background-position: 0% 79%;\n}\n@media (min-width:550px) {\n  #banner-837746537 {\n    padding-top: 600px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\t<section class=\"section\" id=\"section_443482246\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-308634536\">\n\n\t<div id=\"col-856377024\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-1495850763\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1495850763 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<h3 style=\"text-align: center;\">News and articles<\/h3>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:50px;height:2px;background-color:rgb(248, 147, 29);\"><\/div><\/div>\n\n  \n    <div class=\"row large-columns-3 medium-columns-1 small-columns-1\" >\n  <div class=\"col post-item\" data-animate=\"fadeInUp\">\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-bounce box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:70%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/parsian-ebc.com\/en\/prefabricated-buildings\/\" class=\"plain\" aria-label=\"Prefabricated buildings\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"484\" src=\"https:\/\/parsian-ebc.com\/wp-content\/uploads\/2024\/01\/Picture2.jpg\" class=\"attachment-original size-original wp-post-image\" alt=\"\" srcset=\"https:\/\/parsian-ebc.com\/wp-content\/uploads\/2024\/01\/Picture2.jpg 1500w, https:\/\/parsian-ebc.com\/wp-content\/uploads\/2024\/01\/Picture2-300x97.jpg 300w, https:\/\/parsian-ebc.com\/wp-content\/uploads\/2024\/01\/Picture2-1024x330.jpg 1024w, https:\/\/parsian-ebc.com\/wp-content\/uploads\/2024\/01\/Picture2-768x248.jpg 768w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/parsian-ebc.com\/en\/prefabricated-buildings\/\" class=\"plain\">Prefabricated buildings<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tprefabricated building with light structures, made by a system which the walls are made of [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/parsian-ebc.com\/en\/prefabricated-buildings\/\" class=\"button primary is-outline is-small mb-0\">\n\t\t\t\t\t\t\tRead more\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" data-animate=\"fadeInUp\">\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-bounce box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:70%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/parsian-ebc.com\/en\/sandwich-panels\/\" class=\"plain\" aria-label=\"Sandwich panels\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1529\" height=\"868\" src=\"https:\/\/parsian-ebc.com\/wp-content\/uploads\/2024\/01\/panel.jpg\" class=\"attachment-original size-original wp-post-image\" alt=\"\" srcset=\"https:\/\/parsian-ebc.com\/wp-content\/uploads\/2024\/01\/panel.jpg 1529w, https:\/\/parsian-ebc.com\/wp-content\/uploads\/2024\/01\/panel-300x170.jpg 300w, https:\/\/parsian-ebc.com\/wp-content\/uploads\/2024\/01\/panel-1024x581.jpg 1024w, https:\/\/parsian-ebc.com\/wp-content\/uploads\/2024\/01\/panel-768x436.jpg 768w\" sizes=\"auto, (max-width: 1529px) 100vw, 1529px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/parsian-ebc.com\/en\/sandwich-panels\/\" class=\"plain\">Sandwich panels<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tWall sandwich panel: The useful width of sandwich panels in factories is 1.18, 1.14 and [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/parsian-ebc.com\/en\/sandwich-panels\/\" class=\"button primary is-outline is-small mb-0\">\n\t\t\t\t\t\t\tRead more\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" data-animate=\"fadeInUp\">\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-bounce box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:70%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/parsian-ebc.com\/en\/potable-containers\/\" class=\"plain\" aria-label=\"Potable Containers\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2360\" height=\"1512\" src=\"https:\/\/parsian-ebc.com\/wp-content\/uploads\/2024\/01\/DSC02961.jpg\" class=\"attachment-original size-original wp-post-image\" alt=\"\" srcset=\"https:\/\/parsian-ebc.com\/wp-content\/uploads\/2024\/01\/DSC02961.jpg 2360w, https:\/\/parsian-ebc.com\/wp-content\/uploads\/2024\/01\/DSC02961-300x192.jpg 300w, https:\/\/parsian-ebc.com\/wp-content\/uploads\/2024\/01\/DSC02961-1024x656.jpg 1024w, https:\/\/parsian-ebc.com\/wp-content\/uploads\/2024\/01\/DSC02961-768x492.jpg 768w, https:\/\/parsian-ebc.com\/wp-content\/uploads\/2024\/01\/DSC02961-1536x984.jpg 1536w, https:\/\/parsian-ebc.com\/wp-content\/uploads\/2024\/01\/DSC02961-2048x1312.jpg 2048w\" sizes=\"auto, (max-width: 2360px) 100vw, 2360px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/parsian-ebc.com\/en\/potable-containers\/\" class=\"plain\">Potable Containers<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tThe container is a prefabricated structure. Prefabricated container used to be manufactured for temporary accommodation, [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/parsian-ebc.com\/en\/potable-containers\/\" class=\"button primary is-outline is-small mb-0\">\n\t\t\t\t\t\t\tRead more\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_443482246 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-743","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/parsian-ebc.com\/en\/wp-json\/wp\/v2\/pages\/743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/parsian-ebc.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/parsian-ebc.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/parsian-ebc.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/parsian-ebc.com\/en\/wp-json\/wp\/v2\/comments?post=743"}],"version-history":[{"count":2,"href":"https:\/\/parsian-ebc.com\/en\/wp-json\/wp\/v2\/pages\/743\/revisions"}],"predecessor-version":[{"id":745,"href":"https:\/\/parsian-ebc.com\/en\/wp-json\/wp\/v2\/pages\/743\/revisions\/745"}],"wp:attachment":[{"href":"https:\/\/parsian-ebc.com\/en\/wp-json\/wp\/v2\/media?parent=743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}